{"id":87,"count":3,"description":"Venturelli ti offre un'esclusiva selezione di<strong>\u00a0olio extravergine di oliva <\/strong>di qualit\u00e0 superiore: l'<strong>olio extravergine \"Garda Bresciano DOP\"<\/strong> ottenuto da olive del Lago di Garda ed il Mostolio nella latta (da 3 o 5 litri) o in bottiglia in vetro (da 0,5l), un <strong>olio di oliva extravergine<\/strong> ottenuto dalla spremitura di <strong>olive 100% italiane. <\/strong>Scopri il sapore unico dei nostri oli e ricevili comodamente a casa tua in pochi click!","link":"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/","name":"Olio Extravergine di Oliva","slug":"olio-garda","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":1,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olio Extravergine di Oliva Vendita Online I Frantoio Venturelli<\/title>\n<meta name=\"description\" content=\"Olio extra vergine del Garda purissimo, saporito e genuino. Qualit\u00e0 100% italiana. Frantoio con vendita diretta e shop online. Scopri tutti i prodotti!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olio Extravergine di Oliva Vendita Online I Frantoio Venturelli\" \/>\n<meta property=\"og:description\" content=\"Olio extra vergine del Garda purissimo, saporito e genuino. Qualit\u00e0 100% italiana. Frantoio con vendita diretta e shop online. Scopri tutti i prodotti!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/\" \/>\n<meta property=\"og:site_name\" content=\"Venturelli-Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/cat\\\/olio-garda\\\/\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/cat\\\/olio-garda\\\/\",\"name\":\"Olio Extravergine di Oliva Vendita Online I Frantoio Venturelli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#website\"},\"description\":\"Olio extra vergine del Garda purissimo, saporito e genuino. Qualit\u00e0 100% italiana. Frantoio con vendita diretta e shop online. Scopri tutti i prodotti!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/cat\\\/olio-garda\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/cat\\\/olio-garda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Olio Extravergine di Oliva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\",\"name\":\"Venturelli-Italia\",\"description\":\"Vendita on line di Olio Extra Vergine di Oliva del Garda\",\"publisher\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#organization\",\"name\":\"Venturelli-Italia\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/venturelli-al-frantoio-2020.png\",\"contentUrl\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/venturelli-al-frantoio-2020.png\",\"width\":243,\"height\":80,\"caption\":\"Venturelli-Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/venturelliitalia\",\"https:\\\/\\\/www.instagram.com\\\/venturellibontamadeinitaly\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olio Extravergine di Oliva Vendita Online I Frantoio Venturelli","description":"Olio extra vergine del Garda purissimo, saporito e genuino. Qualit\u00e0 100% italiana. Frantoio con vendita diretta e shop online. Scopri tutti i prodotti!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/","og_locale":"it_IT","og_type":"article","og_title":"Olio Extravergine di Oliva Vendita Online I Frantoio Venturelli","og_description":"Olio extra vergine del Garda purissimo, saporito e genuino. Qualit\u00e0 100% italiana. Frantoio con vendita diretta e shop online. Scopri tutti i prodotti!","og_url":"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/","og_site_name":"Venturelli-Italia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/","url":"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/","name":"Olio Extravergine di Oliva Vendita Online I Frantoio Venturelli","isPartOf":{"@id":"https:\/\/venturelli-italia.it\/it\/#website"},"description":"Olio extra vergine del Garda purissimo, saporito e genuino. Qualit\u00e0 100% italiana. Frantoio con vendita diretta e shop online. Scopri tutti i prodotti!","breadcrumb":{"@id":"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/venturelli-italia.it\/it\/cat\/olio-garda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/venturelli-italia.it\/it\/"},{"@type":"ListItem","position":2,"name":"Olio Extravergine di Oliva"}]},{"@type":"WebSite","@id":"https:\/\/venturelli-italia.it\/it\/#website","url":"https:\/\/venturelli-italia.it\/it\/","name":"Venturelli-Italia","description":"Vendita on line di Olio Extra Vergine di Oliva del Garda","publisher":{"@id":"https:\/\/venturelli-italia.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venturelli-italia.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/venturelli-italia.it\/it\/#organization","name":"Venturelli-Italia","url":"https:\/\/venturelli-italia.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/venturelli-italia.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/02\/venturelli-al-frantoio-2020.png","contentUrl":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/02\/venturelli-al-frantoio-2020.png","width":243,"height":80,"caption":"Venturelli-Italia"},"image":{"@id":"https:\/\/venturelli-italia.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/venturelliitalia","https:\/\/www.instagram.com\/venturellibontamadeinitaly\/"]}]}},"_links":{"self":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product_cat\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product?product_cat=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}