{"id":116,"count":4,"description":"Prodotti su base di Mostolio per chi \u00e8 alla ricerca di sapori che diano ai piatti \u201cquel qualcosa in pi\u00f9\u201d. Aglio, basilico, peperoncino, limone, funghi o tartufo: ai men\u00f9 l\u2019ardua sentenza.","link":"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/","name":"Aceti e condimenti","slug":"aceti-condimenti","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":2,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aceti e condimenti | Qualit\u00e0 100% italiana I Frantoio Venturelli<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;aceto e i condimenti Venturelli, per chi \u00e8 alla ricerca di sapori unici e decisi. Aglio, basilico, peperoncino e non solo. Scoprili tutti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aceti e condimenti | Qualit\u00e0 100% italiana I Frantoio Venturelli\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;aceto e i condimenti Venturelli, per chi \u00e8 alla ricerca di sapori unici e decisi. Aglio, basilico, peperoncino e non solo. Scoprili tutti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Venturelli-Italia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/cat\\\/aceti-condimenti\\\/\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/cat\\\/aceti-condimenti\\\/\",\"name\":\"Aceti e condimenti | Qualit\u00e0 100% italiana I Frantoio Venturelli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#website\"},\"description\":\"Scopri l'aceto e i condimenti Venturelli, per chi \u00e8 alla ricerca di sapori unici e decisi. Aglio, basilico, peperoncino e non solo. Scoprili tutti\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/cat\\\/aceti-condimenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/cat\\\/aceti-condimenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aceti e condimenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\",\"name\":\"Venturelli-Italia\",\"description\":\"Vendita on line di Olio Extra Vergine di Oliva del Garda\",\"publisher\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#organization\",\"name\":\"Venturelli-Italia\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/venturelli-al-frantoio-2020.png\",\"contentUrl\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/venturelli-al-frantoio-2020.png\",\"width\":243,\"height\":80,\"caption\":\"Venturelli-Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/venturelliitalia\",\"https:\\\/\\\/www.instagram.com\\\/venturellibontamadeinitaly\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aceti e condimenti | Qualit\u00e0 100% italiana I Frantoio Venturelli","description":"Scopri l'aceto e i condimenti Venturelli, per chi \u00e8 alla ricerca di sapori unici e decisi. Aglio, basilico, peperoncino e non solo. Scoprili tutti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/","og_locale":"it_IT","og_type":"article","og_title":"Aceti e condimenti | Qualit\u00e0 100% italiana I Frantoio Venturelli","og_description":"Scopri l'aceto e i condimenti Venturelli, per chi \u00e8 alla ricerca di sapori unici e decisi. Aglio, basilico, peperoncino e non solo. Scoprili tutti","og_url":"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/","og_site_name":"Venturelli-Italia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/","url":"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/","name":"Aceti e condimenti | Qualit\u00e0 100% italiana I Frantoio Venturelli","isPartOf":{"@id":"https:\/\/venturelli-italia.it\/it\/#website"},"description":"Scopri l'aceto e i condimenti Venturelli, per chi \u00e8 alla ricerca di sapori unici e decisi. Aglio, basilico, peperoncino e non solo. Scoprili tutti","breadcrumb":{"@id":"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/venturelli-italia.it\/it\/cat\/aceti-condimenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/venturelli-italia.it\/it\/"},{"@type":"ListItem","position":2,"name":"Aceti e condimenti"}]},{"@type":"WebSite","@id":"https:\/\/venturelli-italia.it\/it\/#website","url":"https:\/\/venturelli-italia.it\/it\/","name":"Venturelli-Italia","description":"Vendita on line di Olio Extra Vergine di Oliva del Garda","publisher":{"@id":"https:\/\/venturelli-italia.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venturelli-italia.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/venturelli-italia.it\/it\/#organization","name":"Venturelli-Italia","url":"https:\/\/venturelli-italia.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/venturelli-italia.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/02\/venturelli-al-frantoio-2020.png","contentUrl":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/02\/venturelli-al-frantoio-2020.png","width":243,"height":80,"caption":"Venturelli-Italia"},"image":{"@id":"https:\/\/venturelli-italia.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/venturelliitalia","https:\/\/www.instagram.com\/venturellibontamadeinitaly\/"]}]}},"_links":{"self":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product_cat\/116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product?product_cat=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}