{"id":50428,"date":"2020-05-13T09:31:52","date_gmt":"2020-05-13T08:31:52","guid":{"rendered":"https:\/\/venturelli-italia.it\/?post_type=product&#038;p=50428"},"modified":"2026-01-21T14:20:24","modified_gmt":"2026-01-21T13:20:24","slug":"taglolini-alluovo-con-germe-di-grano-gr-250","status":"publish","type":"product","link":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/","title":{"rendered":"Tagliolini all&#8217;uovo con Germe di Grano gr. 250"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>In questi Tagliolini la tradizione della pasta all&#8217;uovo incontra il germe di grano in un connubio vincente. Un prodotto sia nutriente che gustoso.<\/p>\n","protected":false},"featured_media":54144,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[89],"product_tag":[],"class_list":["post-50428","product","type-product","status-publish","has-post-thumbnail","product_cat-pasta-sughi-e-salse","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tagliolini all&#039;uovo con Germe di Grano gr. 250 - Venturelli-Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tagliolini all&#039;uovo con Germe di Grano gr. 250 - Venturelli-Italia\" \/>\n<meta property=\"og:description\" content=\"In questi Tagliolini la tradizione della pasta all&#039;uovo incontra il germe di grano in un connubio vincente. Un prodotto sia nutriente che gustoso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/\" \/>\n<meta property=\"og:site_name\" content=\"Venturelli-Italia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/venturelliitalia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T13:20:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/05\/8001011-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/pasta-sughi-e-salse\\\/taglolini-alluovo-con-germe-di-grano-gr-250\\\/\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/pasta-sughi-e-salse\\\/taglolini-alluovo-con-germe-di-grano-gr-250\\\/\",\"name\":\"Tagliolini all'uovo con Germe di Grano gr. 250 - Venturelli-Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/pasta-sughi-e-salse\\\/taglolini-alluovo-con-germe-di-grano-gr-250\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/pasta-sughi-e-salse\\\/taglolini-alluovo-con-germe-di-grano-gr-250\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/8001011-1.jpg\",\"datePublished\":\"2020-05-13T08:31:52+00:00\",\"dateModified\":\"2026-01-21T13:20:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/pasta-sughi-e-salse\\\/taglolini-alluovo-con-germe-di-grano-gr-250\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/pasta-sughi-e-salse\\\/taglolini-alluovo-con-germe-di-grano-gr-250\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/pasta-sughi-e-salse\\\/taglolini-alluovo-con-germe-di-grano-gr-250\\\/#primaryimage\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/8001011-1.jpg\",\"contentUrl\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/8001011-1.jpg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/pasta-sughi-e-salse\\\/taglolini-alluovo-con-germe-di-grano-gr-250\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tagliolini all&#8217;uovo con Germe di Grano gr. 250\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\",\"name\":\"Venturelli-Italia\",\"description\":\"Vendita on line di Olio Extra Vergine di Oliva del Garda\",\"publisher\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#organization\",\"name\":\"Venturelli-Italia\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/venturelli-al-frantoio-2020.png\",\"contentUrl\":\"https:\\\/\\\/venturelli-italia.it\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/venturelli-al-frantoio-2020.png\",\"width\":243,\"height\":80,\"caption\":\"Venturelli-Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/venturelli-italia.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/venturelliitalia\",\"https:\\\/\\\/www.instagram.com\\\/venturellibontamadeinitaly\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tagliolini all'uovo con Germe di Grano gr. 250 - Venturelli-Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/","og_locale":"it_IT","og_type":"article","og_title":"Tagliolini all'uovo con Germe di Grano gr. 250 - Venturelli-Italia","og_description":"In questi Tagliolini la tradizione della pasta all'uovo incontra il germe di grano in un connubio vincente. Un prodotto sia nutriente che gustoso.","og_url":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/","og_site_name":"Venturelli-Italia","article_publisher":"http:\/\/www.facebook.com\/venturelliitalia","article_modified_time":"2026-01-21T13:20:24+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/05\/8001011-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/","url":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/","name":"Tagliolini all'uovo con Germe di Grano gr. 250 - Venturelli-Italia","isPartOf":{"@id":"https:\/\/venturelli-italia.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/#primaryimage"},"image":{"@id":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/#primaryimage"},"thumbnailUrl":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/05\/8001011-1.jpg","datePublished":"2020-05-13T08:31:52+00:00","dateModified":"2026-01-21T13:20:24+00:00","breadcrumb":{"@id":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/#primaryimage","url":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/05\/8001011-1.jpg","contentUrl":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/05\/8001011-1.jpg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/venturelli-italia.it\/it\/prodotti\/pasta-sughi-e-salse\/taglolini-alluovo-con-germe-di-grano-gr-250\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/venturelli-italia.it\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/venturelli-italia.it\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Tagliolini all&#8217;uovo con Germe di Grano gr. 250"}]},{"@type":"WebSite","@id":"https:\/\/venturelli-italia.it\/it\/#website","url":"https:\/\/venturelli-italia.it\/it\/","name":"Venturelli-Italia","description":"Vendita on line di Olio Extra Vergine di Oliva del Garda","publisher":{"@id":"https:\/\/venturelli-italia.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/venturelli-italia.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/venturelli-italia.it\/it\/#organization","name":"Venturelli-Italia","url":"https:\/\/venturelli-italia.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/venturelli-italia.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/02\/venturelli-al-frantoio-2020.png","contentUrl":"https:\/\/venturelli-italia.it\/wp-content\/uploads\/2020\/02\/venturelli-al-frantoio-2020.png","width":243,"height":80,"caption":"Venturelli-Italia"},"image":{"@id":"https:\/\/venturelli-italia.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/venturelliitalia","https:\/\/www.instagram.com\/venturellibontamadeinitaly\/"]}]}},"_links":{"self":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product\/50428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/comments?post=50428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/media\/54144"}],"wp:attachment":[{"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/media?parent=50428"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product_brand?post=50428"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product_cat?post=50428"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/venturelli-italia.it\/it\/wp-json\/wp\/v2\/product_tag?post=50428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}